{"id":844,"date":"2020-03-12T15:09:06","date_gmt":"2020-03-12T18:09:06","guid":{"rendered":"http:\/\/casex.fxwgah7dpe-v1p3zzzxo3ye.p.runcloud.link\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\/"},"modified":"2020-03-12T15:09:06","modified_gmt":"2020-03-12T18:09:06","slug":"tudo-que-voce-precisa-saber-sobre-coronavirus-2","status":"publish","type":"post","link":"https:\/\/gentell.com.br\/en\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\/","title":{"rendered":"Tudo que voc\u00ea precisa saber sobre Coronav\u00edrus"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Os coronav\u00edrus s\u00e3o uma grande fam\u00edlia viral, conhecidos desde meados de 1960, que causam infec\u00e7\u00f5es respirat\u00f3rias em seres humanos e em animais.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Geralmente, infec\u00e7\u00f5es por coronav\u00edrus causam doen\u00e7as respirat\u00f3rias leves a moderadas, semelhantes a um resfriado comum.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Alguns coronav\u00edrus podem causar doen\u00e7as graves com impacto importante em termos de sa\u00fade p\u00fablica, como a Sars (S\u00edndrome Respirat\u00f3ria Aguda Grave), identificada em 2002 e a Mers (S\u00edndrome Respirat\u00f3ria do Oriente M\u00e9dio), identificada em 2012.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"font-weight: 400;\">Formas de transmiss\u00e3o<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Ainda est\u00e3o investigando as formas de transmiss\u00e3o do novo coronav\u00edrus, mas a contamina\u00e7\u00e3o por contato est\u00e1 ocorrendo. \u00c9 importante observar que a dissemina\u00e7\u00e3o de pessoa para pessoa pode ocorrer de forma continuada.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Alguns v\u00edrus s\u00e3o altamente contagiosos (como o sarampo), outros nem tanto. Mas ainda n\u00e3o est\u00e1 claro com que facilidade o coronav\u00edrus se espalha.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Apesar disso, a transmiss\u00e3o dos coronav\u00edrus costuma ocorrer pelo ar ou por contato pessoal com secre\u00e7\u00f5es contaminadas, sendo:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Por vias respirat\u00f3rias, como pelo ar e por got\u00edculas provenientes de espirros e da fala de indiv\u00edduos infectados;<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Por contato f\u00edsico, como beijos e abra\u00e7os;<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Por meio do contato de superf\u00edcies contaminadas, como segurar em corrim\u00e3o, seguido de contato com a boca, nariz ou olhos.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2><span style=\"font-weight: 400;\">Sintomas<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Os sinais e sintomas cl\u00ednicos s\u00e3o principalmente respirat\u00f3rios, como tosse seca, febre e cansa\u00e7o. Mas alguns pacientes tamb\u00e9m podem sentir dores no corpo, congestionamento nasal, inflama\u00e7\u00e3o na garganta ou diarreia. Nos casos mais graves, que geralmente ocorre em pessoas que j\u00e1 tenham outras doen\u00e7as associadas, h\u00e1 s\u00edndrome respirat\u00f3ria aguda e insufici\u00eancia renal.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"font-weight: 400;\">Principais formas de preven\u00e7\u00e3o<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">O Minist\u00e9rio da Sa\u00fade orienta cuidados b\u00e1sicos para reduzir o risco geral de contrair ou transmitir infec\u00e7\u00f5es respirat\u00f3rias agudas, incluindo o novo coronav\u00edrus. Entre as medidas est\u00e3o:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Lavar as m\u00e3os frequentemente com \u00e1gua e sabonete por pelo menos 20 segundos, respeitando os 5 momentos de higieniza\u00e7\u00e3o. Se n\u00e3o houver \u00e1gua e sabonete, usar um desinfetante para as m\u00e3os \u00e0 base de \u00e1lcool, como \u00e1lcool em gel.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Evitar tocar nos olhos, nariz e boca com as m\u00e3os n\u00e3o lavadas.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Evitar contato pr\u00f3ximo com pessoas doentes.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Ficar em casa quando estiver doente.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Cobrir boca e nariz ao tossir ou espirrar com um len\u00e7o de papel e jogar no lixo.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Limpar e desinfetar objetos e superf\u00edcies tocados com frequ\u00eancia.<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Limpar regularmente o ambiente e mant\u00ea-lo ventilado.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2><span style=\"font-weight: 400;\">Existe tratamento?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">N\u00e3o existe tratamento espec\u00edfico contra o Covid-19, a doen\u00e7a provocada pelo novo coronav\u00edrus. Os pacientes infectados recebem tratamento para aliviar os sintomas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">As medidas adotadas para aliviar os sintomas s\u00e3o:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><strong><a href=\"https:\/\/gentell.com.br\/en\/pacientes\/produtos\/\">Medicamentos<\/a><\/strong> para dor e febre (antit\u00e9rmicos e analg\u00e9sicos);<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Umidificador no quarto ou banho quente para aliviar a dor de garganta e tosse.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Assim que os primeiros sintomas surgirem, \u00e9 fundamental procurar ajuda m\u00e9dica imediata para confirmar diagn\u00f3stico e iniciar o tratamento.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"font-weight: 400;\">Por quanto tempo a doen\u00e7a pode ficar incubada?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">A doen\u00e7a pode ficar incubada at\u00e9 duas semanas ap\u00f3s o contato com o v\u00edrus. O per\u00edodo m\u00e9dio de incuba\u00e7\u00e3o \u00e9 de 5 dias, com intervalo que pode chegar at\u00e9 a 14 dias.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"font-weight: 400;\">Prepara\u00e7\u00e3o do Brasil<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">O governo federal adotou diversas a\u00e7\u00f5es para o monitoramento e o aprimoramento da capacidade de atua\u00e7\u00e3o do pa\u00eds diante do epis\u00f3dio ocorrido na China. Entre essas a\u00e7\u00f5es, est\u00e3o a ado\u00e7\u00e3o das medidas recomendadas pela OMS; a notifica\u00e7\u00e3o da \u00e1rea de portos, aeroportos e fronteiras da Anvisa (Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria); a notifica\u00e7\u00e3o da \u00e1rea de Vigil\u00e2ncia Animal do MAPA (Minist\u00e9rio da Agricultura, Pecu\u00e1ria e Abastecimento); e a notifica\u00e7\u00e3o \u00e0s Secretarias de Sa\u00fade dos estados e munic\u00edpios, demais Secretarias do Minist\u00e9rio da Sa\u00fade e demais \u00f3rg\u00e3os federais com base em dados oficiais, evitando medidas restritivas e desproporcionais em rela\u00e7\u00e3o aos riscos para a sa\u00fade e tr\u00e2nsito.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na pr\u00e1tica, tudo depende da evolu\u00e7\u00e3o dos casos no pa\u00eds. H\u00e1 dois grandes cen\u00e1rios poss\u00edveis na crise atual: um de conten\u00e7\u00e3o, outro de mitiga\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No primeiro, o pa\u00eds passa a ter cada vez mais casos pontuais ligados a pessoas oriundas de outros pa\u00edses, como tem acontecido nos Estados Unidos e no Reino Unido. O Brasil, hoje, est\u00e1 nesse grupo. Neste cen\u00e1rio, a rotina da popula\u00e7\u00e3o em geral praticamente n\u00e3o muda.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O segundo surgir\u00e1 se o v\u00edrus estiver disseminado em uma \u00e1rea mais ampla pelo cont\u00e1gio, o surto estiver instalado no pa\u00eds e a doen\u00e7a passar a ser transmitida com rapidez e volume entre diversas pessoas, como na It\u00e1lia e na China.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Neste cen\u00e1rio, h\u00e1, por exemplo, quarentenas de cidades ou regi\u00f5es, cancelamentos de aulas e eventos p\u00fablicos e implementa\u00e7\u00e3o de trabalho remoto em empresas.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>Fonte: <\/b><a href=\"https:\/\/www.uol.com.br\/vivabem\/noticias\/redacao\/2020\/01\/25\/tire-suas-principais-duvidas-sobre-o-coronavirus-que-se-espalha-pelo-mundo.htm\"><b>https:\/\/www.uol.com.br\/vivabem\/noticias\/redacao\/2020\/01\/25\/tire-suas-principais-duvidas-sobre-o-coronavirus-que-se-espalha-pelo-mundo.htm<\/b><\/a><\/p>\n<p><a href=\"https:\/\/www.bbc.com\/portuguese\/brasil-51673933\"><b>https:\/\/www.bbc.com\/portuguese\/brasil-51673933<\/b><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Os coronav\u00edrus s\u00e3o uma grande fam\u00edlia viral, conhecidos desde meados de 1960, que causam infec\u00e7\u00f5es respirat\u00f3rias em seres humanos e em animais. Geralmente, infec\u00e7\u00f5es por coronav\u00edrus causam doen\u00e7as respirat\u00f3rias leves a moderadas, semelhantes a um resfriado comum.\u00a0 Alguns coronav\u00edrus podem causar doen\u00e7as graves com impacto importante em termos de sa\u00fade p\u00fablica, como a Sars (S\u00edndrome [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":845,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,8],"tags":[55,51,56,57],"class_list":["post-844","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-pacientes","tag-coronavirus","tag-cuidados","tag-prevencao","tag-virus"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tudo que voc\u00ea precisa saber sobre Coronav\u00edrus - Gentell | We make it better<\/title>\n<meta name=\"description\" content=\"Veja tudo que voc\u00ea precisa saber sobre o Coronav\u00edrus. O v\u00edrus que est\u00e1 causando grandes impactos globais e devastando pa\u00edses.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gentell.com.br\/en\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tudo que voc\u00ea precisa saber sobre Coronav\u00edrus - Gentell | We make it better\" \/>\n<meta property=\"og:description\" content=\"Veja tudo que voc\u00ea precisa saber sobre o Coronav\u00edrus. O v\u00edrus que est\u00e1 causando grandes impactos globais e devastando pa\u00edses.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gentell.com.br\/en\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Gentell | We make it better\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-12T18:09:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gentell.com.br\/wp-content\/uploads\/2021\/03\/tudo-que-voce-precisa-saber-sobre-coronavirus-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"602\" \/>\n\t<meta property=\"og:image:height\" content=\"322\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"devrocket\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"devrocket\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gentell.com.br\\\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gentell.com.br\\\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\\\/\"},\"author\":{\"name\":\"devrocket\",\"@id\":\"https:\\\/\\\/gentell.com.br\\\/#\\\/schema\\\/person\\\/d1ebcc1613e23b7a9afd8ad157648dbd\"},\"headline\":\"Tudo que voc\u00ea precisa saber sobre Coronav\u00edrus\",\"datePublished\":\"2020-03-12T18:09:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gentell.com.br\\\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\\\/\"},\"wordCount\":880,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gentell.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gentell.com.br\\\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gentell.com.br\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/tudo-que-voce-precisa-saber-sobre-coronavirus-2.jpg\",\"keywords\":[\"coronav\u00edrus\",\"cuidados\",\"preven\u00e7\u00e3o\",\"v\u00edrus\"],\"articleSection\":[\"Not\u00edcias\",\"Pacientes\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gentell.com.br\\\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gentell.com.br\\\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\\\/\",\"url\":\"https:\\\/\\\/gentell.com.br\\\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\\\/\",\"name\":\"Tudo que voc\u00ea precisa saber sobre Coronav\u00edrus - Gentell | We make it better\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gentell.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gentell.com.br\\\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gentell.com.br\\\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gentell.com.br\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/tudo-que-voce-precisa-saber-sobre-coronavirus-2.jpg\",\"datePublished\":\"2020-03-12T18:09:06+00:00\",\"description\":\"Veja tudo que voc\u00ea precisa saber sobre o Coronav\u00edrus. O v\u00edrus que est\u00e1 causando grandes impactos globais e devastando pa\u00edses.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gentell.com.br\\\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gentell.com.br\\\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/gentell.com.br\\\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gentell.com.br\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/tudo-que-voce-precisa-saber-sobre-coronavirus-2.jpg\",\"contentUrl\":\"https:\\\/\\\/gentell.com.br\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/tudo-que-voce-precisa-saber-sobre-coronavirus-2.jpg\",\"width\":602,\"height\":322},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gentell.com.br\\\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/gentell.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tudo que voc\u00ea precisa saber sobre Coronav\u00edrus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gentell.com.br\\\/#website\",\"url\":\"https:\\\/\\\/gentell.com.br\\\/\",\"name\":\"Gentell | We make it better\",\"description\":\"Bolsa de Colostomia, Curativos e Acess\u00f3rios\",\"publisher\":{\"@id\":\"https:\\\/\\\/gentell.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gentell.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gentell.com.br\\\/#organization\",\"name\":\"Gentell | We make it better\",\"url\":\"https:\\\/\\\/gentell.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/gentell.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gentell.com.br\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Gentell-Logo.png\",\"contentUrl\":\"https:\\\/\\\/gentell.com.br\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Gentell-Logo.png\",\"width\":1024,\"height\":276,\"caption\":\"Gentell | We make it better\"},\"image\":{\"@id\":\"https:\\\/\\\/gentell.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gentell.com.br\\\/#\\\/schema\\\/person\\\/d1ebcc1613e23b7a9afd8ad157648dbd\",\"name\":\"devrocket\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52a32b6a1cba2f7622dd8d29242b066e428387f5a269c2648e097f4726e6167b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52a32b6a1cba2f7622dd8d29242b066e428387f5a269c2648e097f4726e6167b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52a32b6a1cba2f7622dd8d29242b066e428387f5a269c2648e097f4726e6167b?s=96&d=mm&r=g\",\"caption\":\"devrocket\"},\"url\":\"https:\\\/\\\/gentell.com.br\\\/en\\\/author\\\/devrocket\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tudo que voc\u00ea precisa saber sobre Coronav\u00edrus - Gentell | We make it better","description":"Veja tudo que voc\u00ea precisa saber sobre o Coronav\u00edrus. O v\u00edrus que est\u00e1 causando grandes impactos globais e devastando pa\u00edses.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gentell.com.br\/en\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\/","og_locale":"en_US","og_type":"article","og_title":"Tudo que voc\u00ea precisa saber sobre Coronav\u00edrus - Gentell | We make it better","og_description":"Veja tudo que voc\u00ea precisa saber sobre o Coronav\u00edrus. O v\u00edrus que est\u00e1 causando grandes impactos globais e devastando pa\u00edses.","og_url":"https:\/\/gentell.com.br\/en\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\/","og_site_name":"Gentell | We make it better","article_published_time":"2020-03-12T18:09:06+00:00","og_image":[{"width":602,"height":322,"url":"https:\/\/gentell.com.br\/wp-content\/uploads\/2021\/03\/tudo-que-voce-precisa-saber-sobre-coronavirus-2.jpg","type":"image\/jpeg"}],"author":"devrocket","twitter_card":"summary_large_image","twitter_misc":{"Written by":"devrocket","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gentell.com.br\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\/#article","isPartOf":{"@id":"https:\/\/gentell.com.br\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\/"},"author":{"name":"devrocket","@id":"https:\/\/gentell.com.br\/#\/schema\/person\/d1ebcc1613e23b7a9afd8ad157648dbd"},"headline":"Tudo que voc\u00ea precisa saber sobre Coronav\u00edrus","datePublished":"2020-03-12T18:09:06+00:00","mainEntityOfPage":{"@id":"https:\/\/gentell.com.br\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\/"},"wordCount":880,"commentCount":0,"publisher":{"@id":"https:\/\/gentell.com.br\/#organization"},"image":{"@id":"https:\/\/gentell.com.br\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\/#primaryimage"},"thumbnailUrl":"https:\/\/gentell.com.br\/wp-content\/uploads\/2021\/03\/tudo-que-voce-precisa-saber-sobre-coronavirus-2.jpg","keywords":["coronav\u00edrus","cuidados","preven\u00e7\u00e3o","v\u00edrus"],"articleSection":["Not\u00edcias","Pacientes"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gentell.com.br\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gentell.com.br\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\/","url":"https:\/\/gentell.com.br\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\/","name":"Tudo que voc\u00ea precisa saber sobre Coronav\u00edrus - Gentell | We make it better","isPartOf":{"@id":"https:\/\/gentell.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gentell.com.br\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\/#primaryimage"},"image":{"@id":"https:\/\/gentell.com.br\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\/#primaryimage"},"thumbnailUrl":"https:\/\/gentell.com.br\/wp-content\/uploads\/2021\/03\/tudo-que-voce-precisa-saber-sobre-coronavirus-2.jpg","datePublished":"2020-03-12T18:09:06+00:00","description":"Veja tudo que voc\u00ea precisa saber sobre o Coronav\u00edrus. O v\u00edrus que est\u00e1 causando grandes impactos globais e devastando pa\u00edses.","breadcrumb":{"@id":"https:\/\/gentell.com.br\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gentell.com.br\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gentell.com.br\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\/#primaryimage","url":"https:\/\/gentell.com.br\/wp-content\/uploads\/2021\/03\/tudo-que-voce-precisa-saber-sobre-coronavirus-2.jpg","contentUrl":"https:\/\/gentell.com.br\/wp-content\/uploads\/2021\/03\/tudo-que-voce-precisa-saber-sobre-coronavirus-2.jpg","width":602,"height":322},{"@type":"BreadcrumbList","@id":"https:\/\/gentell.com.br\/tudo-que-voce-precisa-saber-sobre-coronavirus-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/gentell.com.br\/"},{"@type":"ListItem","position":2,"name":"Tudo que voc\u00ea precisa saber sobre Coronav\u00edrus"}]},{"@type":"WebSite","@id":"https:\/\/gentell.com.br\/#website","url":"https:\/\/gentell.com.br\/","name":"Gentell | We make it better","description":"Bolsa de Colostomia, Curativos e Acess\u00f3rios","publisher":{"@id":"https:\/\/gentell.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gentell.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/gentell.com.br\/#organization","name":"Gentell | We make it better","url":"https:\/\/gentell.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gentell.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/gentell.com.br\/wp-content\/uploads\/2021\/03\/Gentell-Logo.png","contentUrl":"https:\/\/gentell.com.br\/wp-content\/uploads\/2021\/03\/Gentell-Logo.png","width":1024,"height":276,"caption":"Gentell | We make it better"},"image":{"@id":"https:\/\/gentell.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/gentell.com.br\/#\/schema\/person\/d1ebcc1613e23b7a9afd8ad157648dbd","name":"devrocket","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/52a32b6a1cba2f7622dd8d29242b066e428387f5a269c2648e097f4726e6167b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/52a32b6a1cba2f7622dd8d29242b066e428387f5a269c2648e097f4726e6167b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/52a32b6a1cba2f7622dd8d29242b066e428387f5a269c2648e097f4726e6167b?s=96&d=mm&r=g","caption":"devrocket"},"url":"https:\/\/gentell.com.br\/en\/author\/devrocket\/"}]}},"_links":{"self":[{"href":"https:\/\/gentell.com.br\/en\/wp-json\/wp\/v2\/posts\/844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gentell.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gentell.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gentell.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gentell.com.br\/en\/wp-json\/wp\/v2\/comments?post=844"}],"version-history":[{"count":0,"href":"https:\/\/gentell.com.br\/en\/wp-json\/wp\/v2\/posts\/844\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gentell.com.br\/en\/wp-json\/wp\/v2\/media\/845"}],"wp:attachment":[{"href":"https:\/\/gentell.com.br\/en\/wp-json\/wp\/v2\/media?parent=844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gentell.com.br\/en\/wp-json\/wp\/v2\/categories?post=844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gentell.com.br\/en\/wp-json\/wp\/v2\/tags?post=844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}